{"id":11865,"date":"2023-08-21T10:12:10","date_gmt":"2023-08-21T03:12:10","guid":{"rendered":"http:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2.jpeg"},"modified":"2023-08-21T10:12:10","modified_gmt":"2023-08-21T03:12:10","slug":"apel-pagi-21-agustus-2023-2","status":"inherit","type":"attachment","link":"https:\/\/pn-slawi.go.id\/id\/berita-kegiatan-pengadilan\/apel-pagi-pengadilan-negeri-slawi-34\/attachment\/apel-pagi-21-agustus-2023-2\/","title":{"rendered":"Apel Pagi, 21 Agustus 2023 (2)"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-11865","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-scaled.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"226\" src=\"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-300x226.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-300x226.jpeg 300w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1024x771.jpeg 1024w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-768x578.jpeg 768w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1536x1157.jpeg 1536w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-2048x1542.jpeg 2048w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-510x382.jpeg 510w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1080x813.jpeg 1080w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1280x964.jpeg 1280w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-980x738.jpeg 980w, https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-480x362.jpeg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1928,"file":"2023\/08\/Apel-Pagi-21-Agustus-2023-2-scaled.jpeg","sizes":{"medium":{"file":"Apel-Pagi-21-Agustus-2023-2-300x226.jpeg","width":300,"height":226,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-300x226.jpeg"},"large":{"file":"Apel-Pagi-21-Agustus-2023-2-1024x771.jpeg","width":1024,"height":771,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1024x771.jpeg"},"thumbnail":{"file":"Apel-Pagi-21-Agustus-2023-2-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-150x150.jpeg"},"medium_large":{"file":"Apel-Pagi-21-Agustus-2023-2-768x578.jpeg","width":768,"height":578,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-768x578.jpeg"},"1536x1536":{"file":"Apel-Pagi-21-Agustus-2023-2-1536x1157.jpeg","width":1536,"height":1157,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1536x1157.jpeg"},"2048x2048":{"file":"Apel-Pagi-21-Agustus-2023-2-2048x1542.jpeg","width":2048,"height":1542,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-2048x1542.jpeg"},"et-pb-post-main-image":{"file":"Apel-Pagi-21-Agustus-2023-2-400x250.jpeg","width":400,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-400x250.jpeg"},"et-pb-post-main-image-fullwidth":{"file":"Apel-Pagi-21-Agustus-2023-2-1080x675.jpeg","width":1080,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1080x675.jpeg"},"et-pb-portfolio-image":{"file":"Apel-Pagi-21-Agustus-2023-2-400x284.jpeg","width":400,"height":284,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-400x284.jpeg"},"et-pb-portfolio-module-image":{"file":"Apel-Pagi-21-Agustus-2023-2-510x382.jpeg","width":510,"height":382,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-510x382.jpeg"},"et-pb-portfolio-image-single":{"file":"Apel-Pagi-21-Agustus-2023-2-1080x813.jpeg","width":1080,"height":813,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1080x813.jpeg"},"et-pb-gallery-module-image-portrait":{"file":"Apel-Pagi-21-Agustus-2023-2-400x516.jpeg","width":400,"height":516,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-400x516.jpeg"},"et-pb-post-main-image-fullwidth-large":{"file":"Apel-Pagi-21-Agustus-2023-2-2880x1800.jpeg","width":2880,"height":1800,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-2880x1800.jpeg"},"et-pb-image--responsive--desktop":{"file":"Apel-Pagi-21-Agustus-2023-2-1280x964.jpeg","width":1280,"height":964,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-1280x964.jpeg"},"et-pb-image--responsive--tablet":{"file":"Apel-Pagi-21-Agustus-2023-2-980x738.jpeg","width":980,"height":738,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-980x738.jpeg"},"et-pb-image--responsive--phone":{"file":"Apel-Pagi-21-Agustus-2023-2-480x362.jpeg","width":480,"height":362,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-480x362.jpeg"},"full":{"file":"Apel-Pagi-21-Agustus-2023-2-scaled.jpeg","width":2560,"height":1928,"mime_type":"image\/jpeg","source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-scaled.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"Apel-Pagi-21-Agustus-2023-2.jpeg"},"post":11863,"source_url":"https:\/\/pn-slawi.go.id\/id\/wp-content\/uploads\/2023\/08\/Apel-Pagi-21-Agustus-2023-2-scaled.jpeg","_links":{"self":[{"href":"https:\/\/pn-slawi.go.id\/id\/wp-json\/wp\/v2\/media\/11865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pn-slawi.go.id\/id\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pn-slawi.go.id\/id\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pn-slawi.go.id\/id\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pn-slawi.go.id\/id\/wp-json\/wp\/v2\/comments?post=11865"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":11863,"href":"https:\/\/pn-slawi.go.id\/id\/wp-json\/wp\/v2\/posts\/11863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}